{"id":3924,"date":"2024-07-22T00:58:28","date_gmt":"2024-07-22T06:58:28","guid":{"rendered":"https:\/\/loginta.com\/?page_id=3924"},"modified":"2026-07-02T15:41:24","modified_gmt":"2026-07-02T21:41:24","slug":"maquinaria-pesada-2","status":"publish","type":"page","link":"https:\/\/loginta.com\/en\/maquinaria-pesada-2\/","title":{"rendered":"Heavy Equipment"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-cef93154 alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ee43a231\"><h1 class=\"uagb-heading-text\">Heavy Equipment<\/h1><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e4be775b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-1160787b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title-prefix\">Heavy Equipment<\/h3><h2 class=\"uagb-ifb-title\">Importing to Mexico<\/h2><\/div><p class=\"uagb-ifb-desc\">At LOGINTA, we understand the importance of heavy machinery for the development of large projects in sectors such as construction, mining and agriculture. We specialise in facilitating the importation of heavy machinery into Mexico, ensuring that they arrive on time and comply with all customs regulations.<br><br>With over 25 years of experience in logistics and customs management, we offer a comprehensive service that optimises your supply chain and streamlines the import process, allowing you to focus on what really matters: your business.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9a4bad7b\">\n<div class=\"wp-block-uagb-info-box uagb-block-c55bf804 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M160 48C160 21.49 181.5 0 208 0H256V80C256 88.84 263.2 96 272 96H304C312.8 96 320 88.84 320 80V0H368C394.5 0 416 21.49 416 48V176C416 202.5 394.5 224 368 224H208C181.5 224 160 202.5 160 176V48zM96 288V368C96 376.8 103.2 384 112 384H144C152.8 384 160 376.8 160 368V288H208C234.5 288 256 309.5 256 336V464C256 490.5 234.5 512 208 512H48C21.49 512 0 490.5 0 464V336C0 309.5 21.49 288 48 288H96zM416 288V368C416 376.8 423.2 384 432 384H464C472.8 384 480 376.8 480 368V288H528C554.5 288 576 309.5 576 336V464C576 490.5 554.5 512 528 512H368C341.5 512 320 490.5 320 464V336C320 309.5 341.5 288 368 288H416z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Comprehensive Logistics<\/h3><\/div><p class=\"uagb-ifb-desc\">We coordinate the entire logistics process, from collection in the country of origin to delivery at your final destination in Mexico.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-14f4c019 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Selected Partners<\/h3><\/div><p class=\"uagb-ifb-desc\">We have a wide network of qualified suppliers, guaranteeing quality and reliability.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-639134ac uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M448 336v-288C448 21.49 426.5 0 400 0H96C42.98 0 0 42.98 0 96v320c0 53.02 42.98 96 96 96h320c17.67 0 32-14.33 32-31.1c0-11.72-6.607-21.52-16-27.1v-81.36C441.8 362.8 448 350.2 448 336zM143.1 128h192C344.8 128 352 135.2 352 144C352 152.8 344.8 160 336 160H143.1C135.2 160 128 152.8 128 144C128 135.2 135.2 128 143.1 128zM143.1 192h192C344.8 192 352 199.2 352 208C352 216.8 344.8 224 336 224H143.1C135.2 224 128 216.8 128 208C128 199.2 135.2 192 143.1 192zM384 448H96c-17.67 0-32-14.33-32-32c0-17.67 14.33-32 32-32h288V448z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Documentation Management<\/h3><\/div><p class=\"uagb-ifb-desc\">We take care of all the necessary import documentation, including permits, certifications and registrations.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns has-ast-global-color-5-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-uagb-info-box uagb-block-bdc87ec8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title-prefix\">Catalogues<\/h3><h2 class=\"uagb-ifb-title\">Qualified Suppliers<\/h2><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0b0d98a8 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-635685da\">\n<div class=\"wp-block-uagb-container uagb-block-624115db\">\n<div class=\"wp-block-uagb-container uagb-block-17471787\">\n<div class=\"wp-block-uagb-image uagb-block-f78e0012 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2023\/10\/HENGWANG-1-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2023\/10\/HENGWANG-1.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2023\/10\/HENGWANG-1-150x150.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2023\/10\/HENGWANG-1-1024x1024.png\" alt=\"HENGWANG\" class=\"uag-image-2959 lazyload\" width=\"150\" height=\"150\" title=\"HENGWANG\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hwchinamachinery.com\/\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">Hengwang<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e270f734\">\n<div class=\"wp-block-uagb-container uagb-block-4b71b3cc\">\n<div class=\"wp-block-uagb-image uagb-block-d72b33b2 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/04\/Fusion-Machinery-1-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2024\/04\/Fusion-Machinery-1.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2024\/04\/Fusion-Machinery-1-1024x1024.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/04\/Fusion-Machinery-1-1024x1024.png\" alt=\"FUSION MACHINERY\" class=\"uag-image-3239 lazyload\" width=\"150\" height=\"150\" title=\"Fusion Machinery\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/04\/Catalog-All-products-comprimido.pdf\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">Fusion Machinery Catalog<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5ccd395d\">\n<div class=\"wp-block-uagb-container uagb-block-1d16a81a\">\n<div class=\"wp-block-uagb-image uagb-block-2a3d8ad3 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/06\/LOGINTA-3-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2024\/06\/LOGINTA-3.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2024\/06\/LOGINTA-3-1024x1024.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/06\/LOGINTA-3-1024x1024.png\" alt=\"HAI ROLL FONE\" class=\"uag-image-3295 lazyload\" width=\"150\" height=\"150\" title=\"HAI ROLL FONE\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/06\/\u58a8\u897f\u54e5\u5c55\u4f1a\u6837\u518c.pdf\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">Precision Machinery<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66180854\">\n<div class=\"wp-block-uagb-container uagb-block-410db547\">\n<div class=\"wp-block-uagb-container uagb-block-414d5f75\">\n<div class=\"wp-block-uagb-image uagb-block-2a2df53b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/09\/Hunsone-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2024\/09\/Hunsone.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2024\/09\/Hunsone.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/09\/Hunsone-1024x1024.png\" alt=\"\" class=\"uag-image-4127 lazyload\" width=\"150\" height=\"150\" title=\"Hunsone\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/09\/HUNSONE-CATALOG.pdf\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">HUNSONE CATALOG<\/mark><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/11\/HUNSONE-CATALOG-1.pdf\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">SHEET METAL WORKING MACHINES HUNSONE CATALOG <\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-705a8b8e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-c3bb1dc6\">\n<div class=\"wp-block-uagb-container uagb-block-0d4953cb\">\n<div class=\"wp-block-uagb-container uagb-block-7078306e\">\n<div class=\"wp-block-uagb-image uagb-block-5b4c6483 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/10\/Ruilan-Machinery-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2024\/10\/Ruilan-Machinery.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2024\/10\/Ruilan-Machinery.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/10\/Ruilan-Machinery-1024x1024.png\" alt=\"\" class=\"uag-image-4156 lazyload\" width=\"150\" height=\"150\" title=\"Ruilan Machinery\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">Ruilan Machinery<\/mark> <a href=\"https:\/\/loginta.com\/wp-content\/uploads\/2024\/10\/\u4ea7\u54c1\u753b\u518c2.pdf\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-8-color\">Excavator Product Brochure<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fcb5b287\">\n<div class=\"wp-block-uagb-image uagb-block-7c562162 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2025\/08\/ARTUS-1024x576.png ,https:\/\/loginta.com\/wp-content\/uploads\/2025\/08\/ARTUS.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2025\/08\/ARTUS.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2025\/08\/ARTUS-1024x576.png\" alt=\"\" class=\"uag-image-4389 lazyload\" width=\"190\" height=\"190\" title=\"ARTUS\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 190px; --smush-placeholder-aspect-ratio: 190\/190;\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1Utb4Kiq_IFk_zq8X03S8oDG9CV3SyT5V\/view?usp=sharing\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-2-color\">ARTUS HYDRAULIC BREAKING HAMMER<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-80e05152\">\n<div class=\"wp-block-uagb-image uagb-block-f4272831 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2026\/06\/HUATENG-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2026\/06\/HUATENG.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2026\/06\/HUATENG.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2026\/06\/HUATENG-1024x1024.png\" alt=\"\" class=\"uag-image-4444 lazyload\" width=\"209\" height=\"249\" title=\"HUATENG\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 209px; --smush-placeholder-aspect-ratio: 209\/249;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7ff1fb01\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1llOOasGibCZXwtV2FyjL-GRe-A733Ai7\/view?usp=sharing\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-2-color\">Stacker Catalogs<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-34e56e0a\">\n<div class=\"wp-block-uagb-container uagb-block-b6e7a62e\">\n<div class=\"wp-block-uagb-image uagb-block-9cd4ab25 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/loginta.com\/wp-content\/uploads\/2026\/07\/TDER-1024x1024.png ,https:\/\/loginta.com\/wp-content\/uploads\/2026\/07\/TDER.png 780w, https:\/\/loginta.com\/wp-content\/uploads\/2026\/07\/TDER.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/loginta.com\/wp-content\/uploads\/2026\/07\/TDER-1024x1024.png\" alt=\"\" class=\"uag-image-4469 lazyload\" width=\"200\" height=\"200\" title=\"TDER\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/200;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-319f418f\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1MshrIkAdDGgP4nykTZZ4MwA4H7mxeq3B\/view?usp=sharing\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-2-color\">TDER Electric Stacker Catalog<\/mark><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1DlexqCM_dzZKgzY3Daj3VHke97J0b4tv\/view?usp=sharing\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-2-color\">TDER Brochure<\/mark><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f80f4632 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-a545a0b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-01c78ceb uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M160 0C177.7 0 192 14.33 192 32V67.68C193.6 67.89 195.1 68.12 196.7 68.35C207.3 69.93 238.9 75.02 251.9 78.31C268.1 82.65 279.4 100.1 275 117.2C270.7 134.3 253.3 144.7 236.1 140.4C226.8 137.1 198.5 133.3 187.3 131.7C155.2 126.9 127.7 129.3 108.8 136.5C90.52 143.5 82.93 153.4 80.92 164.5C78.98 175.2 80.45 181.3 82.21 185.1C84.1 189.1 87.79 193.6 95.14 198.5C111.4 209.2 136.2 216.4 168.4 225.1L171.2 225.9C199.6 233.6 234.4 243.1 260.2 260.2C274.3 269.6 287.6 282.3 295.8 299.9C304.1 317.7 305.9 337.7 302.1 358.1C295.1 397 268.1 422.4 236.4 435.6C222.8 441.2 207.8 444.8 192 446.6V480C192 497.7 177.7 512 160 512C142.3 512 128 497.7 128 480V445.1C127.6 445.1 127.1 444.1 126.7 444.9L126.5 444.9C102.2 441.1 62.07 430.6 35 418.6C18.85 411.4 11.58 392.5 18.76 376.3C25.94 360.2 44.85 352.9 60.1 360.1C81.9 369.4 116.3 378.5 136.2 381.6C168.2 386.4 194.5 383.6 212.3 376.4C229.2 369.5 236.9 359.5 239.1 347.5C241 336.8 239.6 330.7 237.8 326.9C235.9 322.9 232.2 318.4 224.9 313.5C208.6 302.8 183.8 295.6 151.6 286.9L148.8 286.1C120.4 278.4 85.58 268.9 59.76 251.8C45.65 242.4 32.43 229.7 24.22 212.1C15.89 194.3 14.08 174.3 17.95 153C25.03 114.1 53.05 89.29 85.96 76.73C98.98 71.76 113.1 68.49 128 66.73V32C128 14.33 142.3 0 160 0V0z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">512+<\/h2><\/div><p class=\"uagb-ifb-desc\">Successful Imports in the Last Year<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-3d9017cc uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path d=\"M319.9 320c57.41 0 103.1-46.56 103.1-104c0-57.44-46.54-104-103.1-104c-57.41 0-103.1 46.56-103.1 104C215.9 273.4 262.5 320 319.9 320zM369.9 352H270.1C191.6 352 128 411.7 128 485.3C128 500.1 140.7 512 156.4 512h327.2C499.3 512 512 500.1 512 485.3C512 411.7 448.4 352 369.9 352zM512 160c44.18 0 80-35.82 80-80S556.2 0 512 0c-44.18 0-80 35.82-80 80S467.8 160 512 160zM183.9 216c0-5.449 .9824-10.63 1.609-15.91C174.6 194.1 162.6 192 149.9 192H88.08C39.44 192 0 233.8 0 285.3C0 295.6 7.887 304 17.62 304h199.5C196.7 280.2 183.9 249.7 183.9 216zM128 160c44.18 0 80-35.82 80-80S172.2 0 128 0C83.82 0 48 35.82 48 80S83.82 160 128 160zM551.9 192h-61.84c-12.8 0-24.88 3.037-35.86 8.24C454.8 205.5 455.8 210.6 455.8 216c0 33.71-12.78 64.21-33.16 88h199.7C632.1 304 640 295.6 640 285.3C640 233.8 600.6 192 551.9 192z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">27+<\/h2><\/div><p class=\"uagb-ifb-desc\">Strategic Connections<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-e2303089 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M0 80C0 53.49 21.49 32 48 32H144C170.5 32 192 53.49 192 80V96H384V80C384 53.49 405.5 32 432 32H528C554.5 32 576 53.49 576 80V176C576 202.5 554.5 224 528 224H432C405.5 224 384 202.5 384 176V160H192V176C192 177.7 191.9 179.4 191.7 180.1L272 288H368C394.5 288 416 309.5 416 336V432C416 458.5 394.5 480 368 480H272C245.5 480 224 458.5 224 432V336C224 334.3 224.1 332.6 224.3 331L144 224H48C21.49 224 0 202.5 0 176V80z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">8+<\/h2><\/div><p class=\"uagb-ifb-desc\">Industrial Sectors<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-720e491a uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M288 358.3c13.98-8.088 17.53-30.04 28.88-41.39c11.35-11.35 33.3-14.88 41.39-28.87c7.98-13.79 .1658-34.54 4.373-50.29C366.7 222.5 383.1 208.5 383.1 192c0-16.5-17.27-30.52-21.34-45.73c-4.207-15.75 3.612-36.5-4.365-50.29c-8.086-13.98-30.03-17.52-41.38-28.87c-11.35-11.35-14.89-33.3-28.87-41.39c-13.79-7.979-34.54-.1637-50.29-4.375C222.5 17.27 208.5 0 192 0C175.5 0 161.5 17.27 146.3 21.34C130.5 25.54 109.8 17.73 95.98 25.7C82 33.79 78.46 55.74 67.11 67.08C55.77 78.43 33.81 81.97 25.72 95.95C17.74 109.7 25.56 130.5 21.35 146.2C17.27 161.5 .0008 175.5 .0008 192c0 16.5 17.27 30.52 21.34 45.73c4.207 15.75-3.615 36.5 4.361 50.29C33.8 302 55.74 305.5 67.08 316.9c11.35 11.35 14.89 33.3 28.88 41.4c13.79 7.979 34.53 .1582 50.28 4.369C161.5 366.7 175.5 384 192 384c16.5 0 30.52-17.27 45.74-21.34C253.5 358.5 274.2 366.3 288 358.3zM112 192c0-44.27 35.81-80 80-80s80 35.73 80 80c0 44.17-35.81 80-80 80S112 236.2 112 192zM1.719 433.2c-3.25 8.188-1.781 17.48 3.875 24.25c5.656 6.75 14.53 9.898 23.12 8.148l45.19-9.035l21.43 42.27C99.46 507 107.6 512 116.7 512c.3438 0 .6641-.0117 1.008-.0273c9.5-.375 17.65-6.082 21.24-14.88l33.58-82.08c-53.71-4.639-102-28.12-138.2-63.95L1.719 433.2zM349.6 351.1c-36.15 35.83-84.45 59.31-138.2 63.95l33.58 82.08c3.594 8.797 11.74 14.5 21.24 14.88C266.6 511.1 266.1 512 267.3 512c9.094 0 17.23-4.973 21.35-13.14l21.43-42.28l45.19 9.035c8.594 1.75 17.47-1.398 23.12-8.148c5.656-6.766 7.125-16.06 3.875-24.25L349.6 351.1z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">25+<\/h2><\/div><p class=\"uagb-ifb-desc\">Years of Experience<\/p><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Heavy Equipment<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3924","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"claudia","author_link":"https:\/\/loginta.com\/en\/author\/claudia\/"},"uagb_comment_info":0,"uagb_excerpt":"Maquinaria Pesada","_links":{"self":[{"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/pages\/3924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/comments?post=3924"}],"version-history":[{"count":14,"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/pages\/3924\/revisions"}],"predecessor-version":[{"id":4470,"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/pages\/3924\/revisions\/4470"}],"wp:attachment":[{"href":"https:\/\/loginta.com\/en\/wp-json\/wp\/v2\/media?parent=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}